{"id":51267,"date":"2026-07-31T16:54:09","date_gmt":"2026-07-31T19:54:09","guid":{"rendered":"https:\/\/www.icpa-gz.org.py\/DE\/?post_type=tribe_events&#038;p=51267"},"modified":"2026-07-31T16:54:09","modified_gmt":"2026-07-31T19:54:09","slug":"eichnen-und-malkurs-8-9","status":"publish","type":"tribe_events","link":"https:\/\/www.icpa-gz.org.py\/DE\/evento\/eichnen-und-malkurs-8-9\/","title":{"rendered":"eichnen- und Malkurs 8\/9"},"content":{"rendered":"<p>Unter der Leitung des erfahrenen bildenden K\u00fcnstlers Gabriel Brizuela Santom\u00e9 werden die Teilnehmer:innen durch verschiedene Techniken wie Graphit, Pastell, Aquarell, \u00d6lpastell, Tusche, Mischtechniken und andere gef\u00fchrt. Sie entwickeln Themen auf figurativer als auch auf abstrakter Ebene, die von der menschlichen Figur bis zu Stillleben und Natur reichen.<\/p>\n<p>Gabriel Brizuela Santom\u00e9 hatte \u00fcber hundert Ausstellungen in Paraguay und im Ausland, wobei er unser Land mehrfach in Brasilien, Argentinien, Uruguay, Spanien, Portugal, Italien und den USA bei Biennalen, Festivals, Wettbewerben usw. vertreten hat. Er ist der Gr\u00fcnder von MAD, dem Museum f\u00fcr digitale Kunst, dem ersten Portal f\u00fcr visuelle Kunst in Paraguay und Amerika, der ersten Fakult\u00e4t f\u00fcr Grafikdesign (UCA) in unserem Land, des Kreises der Kreativen von Paraguay, des Aquarellkollektivs Medium Aquae, des j\u00e4hrlichen Aquarellsalons und er ist der Leiter von Paraguay f\u00fcr die IWS, International Watercolour Society.<\/p>\n<p>Die Workshops finden jeden Dienstag von 15:00 Uhr bis 18:00. Samstag von 09:00 Uhr bis 12:00 Uhr.<\/p>\n<p>Telefonische Anfragen gerne an das ICPA-GZ |\u00a0<a href=\"tel:+59521224455\">(021) 22 44 55<\/a><\/p>\n<p>Whatsapp ICPA |\u00a0<a href=\"http:\/\/wa.me\/595983307150\">+595983307150<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unter der Leitung des erfahrenen bildenden K\u00fcnstlers Gabriel Brizuela Santom\u00e9 werden die Teilnehmer:innen durch verschiedene Techniken wie Graphit, Pastell, Aquarell,<\/p>\n","protected":false},"author":1,"featured_media":51111,"template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_tribe_events_status":"","_tribe_events_status_reason":"","_joinchat":[],"footnotes":""},"tags":[],"tribe_events_cat":[50,51,77,34],"class_list":["post-51267","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-kultur","tribe_events_cat-kunst","tribe_events_cat-prasenzveranstaltung","tribe_events_cat-workshop","cat_kultur","cat_kunst","cat_prasenzveranstaltung","cat_workshop"],"_links":{"self":[{"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/tribe_events\/51267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/tribe_events\/51267\/revisions"}],"predecessor-version":[{"id":51281,"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/tribe_events\/51267\/revisions\/51281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/media\/51111"}],"wp:attachment":[{"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/media?parent=51267"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/tags?post=51267"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.icpa-gz.org.py\/DE\/wp-json\/wp\/v2\/tribe_events_cat?post=51267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}